{"id":10118,"date":"2021-03-31T02:53:27","date_gmt":"2021-03-31T02:53:27","guid":{"rendered":"https:\/\/pbt.kedah.gov.my\/?page_id=10118"},"modified":"2024-05-27T20:00:51","modified_gmt":"2024-05-27T12:00:51","slug":"piagam-pelanggan-mds","status":"publish","type":"page","link":"https:\/\/pbt.kedah.gov.my\/index.php\/piagam-pelanggan-mds\/","title":{"rendered":"Piagam Pelanggan"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"10118\" class=\"elementor elementor-10118\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c839341 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"c839341\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a6b6f19\" data-id=\"a6b6f19\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1250ca6 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"1250ca6\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-f2f4cc3\" data-id=\"f2f4cc3\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b41f84a elementor-widget elementor-widget-shortcode\" data-id=\"b41f84a\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div id=\"mega-menu-wrap-max_mega_menu_8\" class=\"mega-menu-wrap\"><div class=\"mega-menu-toggle\"><div class=\"mega-toggle-blocks-left\"><\/div><div class=\"mega-toggle-blocks-center\"><\/div><div class=\"mega-toggle-blocks-right\"><div class='mega-toggle-block mega-menu-toggle-animated-block mega-toggle-block-0' id='mega-toggle-block-0'><button aria-label=\"Toggle Menu\" class=\"mega-toggle-animated mega-toggle-animated-slider\" type=\"button\" aria-haspopup=\"true\" aria-expanded=\"false\" aria-controls=\"mega-menu-max_mega_menu_8\">\n                  <span class=\"mega-toggle-animated-box\">\n                    <span class=\"mega-toggle-animated-inner\"><\/span>\n                  <\/span>\n                <\/button><\/div><\/div><\/div><ul id=\"mega-menu-max_mega_menu_8\" class=\"mega-menu max-mega-menu mega-menu-horizontal mega-no-js\" data-event=\"hover_intent\" data-effect=\"fade_up\" data-effect-speed=\"200\" data-effect-mobile=\"disabled\" data-effect-speed-mobile=\"0\" data-mobile-force-width=\"false\" data-second-click=\"go\" data-document-click=\"collapse\" data-vertical-behaviour=\"standard\" data-breakpoint=\"768\" data-unbind=\"true\" data-mobile-state=\"collapse_all\" data-mobile-direction=\"vertical\" data-hover-intent-timeout=\"300\" data-hover-intent-interval=\"100\"><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-align-bottom-left mega-menu-flyout mega-menu-item-2857\" id=\"mega-menu-item-2857\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/majlis-daerah-sik\/\">LAMAN UTAMA MDS<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-post_type mega-menu-item-object-page mega-menu-item-has-children mega-align-bottom-left mega-menu-flyout mega-menu-item-15377\" id=\"mega-menu-item-15377\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/md-sik\/\" aria-expanded=\"false\" aria-controls=\"mega-sub-menu-15377\">MD Sik<span class=\"mega-indicator\" aria-hidden=\"true\"><\/span><\/a>\n<ul class=\"mega-sub-menu\" id='mega-sub-menu-15377'>\n<li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-has-children mega-menu-item-2858\" id=\"mega-menu-item-2858\"><a class=\"mega-menu-link\" href=\"#\" aria-expanded=\"false\" aria-controls=\"mega-sub-menu-2858\">PROFIL<span class=\"mega-indicator\" aria-hidden=\"true\"><\/span><\/a>\n\t<ul class=\"mega-sub-menu\" id='mega-sub-menu-2858'>\n<li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2859\" id=\"mega-menu-item-2859\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/latar-belakang-mds\/\">Latar Belakang<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2860\" id=\"mega-menu-item-2860\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/visi-misi-mds\/\">Visi & Misi<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2861\" id=\"mega-menu-item-2861\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/objektif-mds-2\/\">Objektif<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2862\" id=\"mega-menu-item-2862\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/fungsi-mds-2\/\">Fungsi<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2863\" id=\"mega-menu-item-2863\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/logo-mds\/\">Logo<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2864\" id=\"mega-menu-item-2864\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/piagam-pelanggan-mds\/\">Piagam Pelanggan<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-post_type mega-menu-item-object-page mega-menu-item-43501\" id=\"mega-menu-item-43501\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/prestasi-piagam-pelanggan-md-sik-2\/\">Prestasi Piagam Pelanggan 2026<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-post_type mega-menu-item-object-page mega-menu-item-15411\" id=\"mega-menu-item-15411\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/prestasi-piagam-pelanggan-md-sik\/\">Arkib Prestasi Piagam Pelanggan<\/a><\/li>\t<\/ul>\n<\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-has-children mega-menu-item-2865\" id=\"mega-menu-item-2865\"><a class=\"mega-menu-link\" href=\"#\" aria-expanded=\"false\" aria-controls=\"mega-sub-menu-2865\">PENGURUSAN<span class=\"mega-indicator\" aria-hidden=\"true\"><\/span><\/a>\n\t<ul class=\"mega-sub-menu\" id='mega-sub-menu-2865'>\n<li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2866\" id=\"mega-menu-item-2866\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/perutusan-ydp-mds-2\/\">Perutusan YDP<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2867\" id=\"mega-menu-item-2867\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/profil-ydp-mds\/\">Profil YDP<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-post_type mega-menu-item-object-page mega-menu-item-18527\" id=\"mega-menu-item-18527\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/profil-ahli-majlis\/\">Profil Ahli Majlis<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-12372\" id=\"mega-menu-item-12372\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/ketua-pegawai-maklumat-cio-mds\/\">Ketua Pegawai Maklumat (CIO)<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2869\" id=\"mega-menu-item-2869\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/carta-organisasi-mds\/\">Carta Organisasi<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2870\" id=\"mega-menu-item-2870\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/direktori-staf\/\">Direktori Staf<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2871\" id=\"mega-menu-item-2871\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/senarai-jabatan-mds\/\">Senarai Jabatan<\/a><\/li>\t<\/ul>\n<\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-has-children mega-menu-item-2883\" id=\"mega-menu-item-2883\"><a class=\"mega-menu-link\" href=\"#\" aria-expanded=\"false\" aria-controls=\"mega-sub-menu-2883\">SUMBER<span class=\"mega-indicator\" aria-hidden=\"true\"><\/span><\/a>\n\t<ul class=\"mega-sub-menu\" id='mega-sub-menu-2883'>\n<li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2884\" id=\"mega-menu-item-2884\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/perundangan-mds\/\">Perundangan<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2885\" id=\"mega-menu-item-2885\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/pekeliling-panduan-mds\/\">Pekeliling & Panduan<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2886\" id=\"mega-menu-item-2886\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/penerbitan-mds\/\">Penerbitan<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-has-children mega-menu-item-2887\" id=\"mega-menu-item-2887\"><a class=\"mega-menu-link\" href=\"#\" aria-expanded=\"false\" aria-controls=\"mega-sub-menu-2887\">Statistik E-Perkhidmatan<span class=\"mega-indicator\" aria-hidden=\"true\"><\/span><\/a>\n\t\t<ul class=\"mega-sub-menu\" id='mega-sub-menu-2887'>\n<li class=\"mega-menu-item mega-menu-item-type-post_type mega-menu-item-object-page mega-menu-item-43495\" id=\"mega-menu-item-43495\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/statistik-e-perkhidmatan-mds-2\/\">2026<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-12390\" id=\"mega-menu-item-12390\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/statistik-e-perkhidmatan-mds\/\">2025<\/a><\/li>\t\t<\/ul>\n<\/li>\t<\/ul>\n<\/li><\/ul>\n<\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-has-children mega-align-bottom-left mega-menu-flyout mega-menu-item-2888\" id=\"mega-menu-item-2888\"><a class=\"mega-menu-link\" href=\"#\" aria-expanded=\"false\" aria-controls=\"mega-sub-menu-2888\">RAKYAT<span class=\"mega-indicator\" aria-hidden=\"true\"><\/span><\/a>\n<ul class=\"mega-sub-menu\" id='mega-sub-menu-2888'>\n<li class=\"mega-menu-item mega-menu-item-type-post_type mega-menu-item-object-page mega-menu-item-35644\" id=\"mega-menu-item-35644\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/peluang-kerjaya\/\">Peluang Kerjaya<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2889\" id=\"mega-menu-item-2889\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/muat-turun-borang\/\">Muat Turun Borang<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-post_type mega-menu-item-object-page mega-menu-item-126555\" id=\"mega-menu-item-126555\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/dataset-negeri-kedah-6\/\">Dataset Negeri Kedah<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2891\" id=\"mega-menu-item-2891\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/manual-pengguna-4\/\">Manual Pengguna<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-has-children mega-menu-item-2892\" id=\"mega-menu-item-2892\"><a class=\"mega-menu-link\" href=\"#\" aria-expanded=\"false\" aria-controls=\"mega-sub-menu-2892\">Perkhidmatan<span class=\"mega-indicator\" aria-hidden=\"true\"><\/span><\/a>\n\t<ul class=\"mega-sub-menu\" id='mega-sub-menu-2892'>\n<li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2895\" id=\"mega-menu-item-2895\"><a class=\"mega-menu-link\" href=\"#\">Pengurusan Sisa<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2896\" id=\"mega-menu-item-2896\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/kaunter-kaunter-mds\/\">Kaunter-kaunter<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2897\" id=\"mega-menu-item-2897\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/aduan-mds\/\">Aduan<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2898\" id=\"mega-menu-item-2898\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/pelesenan-mds\/\">Pelesenan<\/a><\/li>\t<\/ul>\n<\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-has-children mega-menu-item-2901\" id=\"mega-menu-item-2901\"><a class=\"mega-menu-link\" href=\"#\" aria-expanded=\"false\" aria-controls=\"mega-sub-menu-2901\">E-Perkhidmatan<span class=\"mega-indicator\" aria-hidden=\"true\"><\/span><\/a>\n\t<ul class=\"mega-sub-menu\" id='mega-sub-menu-2901'>\n<li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-12354\" id=\"mega-menu-item-12354\"><a class=\"mega-menu-link\" href=\"https:\/\/pbtpay.kpkt.gov.my\/\">PBTPay<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2902\" id=\"mega-menu-item-2902\"><a class=\"mega-menu-link\" href=\"https:\/\/elesen.kpkt.gov.my\/\">Sistem eLesen<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2905\" id=\"mega-menu-item-2905\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/ikedah-3\/\">iKedah<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2907\" id=\"mega-menu-item-2907\"><a class=\"mega-menu-link\" href=\"https:\/\/epsm.kedah.gov.my\/login.php\">Sistem ePSM<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2904\" id=\"mega-menu-item-2904\"><a class=\"mega-menu-link\" href=\"#\">i-Tegur Aduan Awam<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2899\" id=\"mega-menu-item-2899\"><a class=\"mega-menu-link\" href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSdPa73RXJD7Hilvk-mDVMARcOcu8gWd_WkPQhpdn-2ahRRdKg\/viewform\">Sistem Sewaan Fasiliti<\/a><\/li>\t<\/ul>\n<\/li><\/ul>\n<\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-has-children mega-align-bottom-left mega-menu-flyout mega-menu-item-2910\" id=\"mega-menu-item-2910\"><a class=\"mega-menu-link\" href=\"#\" aria-expanded=\"false\" aria-controls=\"mega-sub-menu-2910\">PERNIAGAAN<span class=\"mega-indicator\" aria-hidden=\"true\"><\/span><\/a>\n<ul class=\"mega-sub-menu\" id='mega-sub-menu-2910'>\n<li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2911\" id=\"mega-menu-item-2911\"><a class=\"mega-menu-link\" href=\"#\">Permohonan<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2912\" id=\"mega-menu-item-2912\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/pelesenan-mds\/\">Pelesenan<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2913\" id=\"mega-menu-item-2913\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/sewaan-mds\/\">Sewaan<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2914\" id=\"mega-menu-item-2914\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/tender-sebutharga-mds\/\">Tender & Sebutharga<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-12348\" id=\"mega-menu-item-12348\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/arkib-tender-sebutharga-mds\/\">Arkib Tender Sebutharga<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-has-children mega-menu-item-2915\" id=\"mega-menu-item-2915\"><a class=\"mega-menu-link\" href=\"#\" aria-expanded=\"false\" aria-controls=\"mega-sub-menu-2915\">Perkhidmatan Pembangunan Ekonomi<span class=\"mega-indicator\" aria-hidden=\"true\"><\/span><\/a>\n\t<ul class=\"mega-sub-menu\" id='mega-sub-menu-2915'>\n<li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2916\" id=\"mega-menu-item-2916\"><a class=\"mega-menu-link\" href=\"#\">Kawasan Perindustrian<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2917\" id=\"mega-menu-item-2917\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/premis-perniagaan-mds\/\">Premis Perniagaan<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2918\" id=\"mega-menu-item-2918\"><a class=\"mega-menu-link\" href=\"#\">Peluang Perniagaan<\/a><\/li>\t<\/ul>\n<\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-has-children mega-menu-item-2919\" id=\"mega-menu-item-2919\"><a class=\"mega-menu-link\" href=\"#\" aria-expanded=\"false\" aria-controls=\"mega-sub-menu-2919\">Perundangan<span class=\"mega-indicator\" aria-hidden=\"true\"><\/span><\/a>\n\t<ul class=\"mega-sub-menu\" id='mega-sub-menu-2919'>\n<li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2920\" id=\"mega-menu-item-2920\"><a class=\"mega-menu-link\" href=\"#\">Perundangan Perniagaan<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2921\" id=\"mega-menu-item-2921\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/akta-mds\/\">Akta<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2922\" id=\"mega-menu-item-2922\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/undang-undang-kecil-mds\/\">Undang-undang Kecil<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2923\" id=\"mega-menu-item-2923\"><a class=\"mega-menu-link\" href=\"#\">Perintah<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2924\" id=\"mega-menu-item-2924\"><a class=\"mega-menu-link\" href=\"#\">Kaedah<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2925\" id=\"mega-menu-item-2925\"><a class=\"mega-menu-link\" href=\"#\">Lembaga Rayuan<\/a><\/li>\t<\/ul>\n<\/li><\/ul>\n<\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-has-children mega-align-bottom-left mega-menu-flyout mega-menu-item-2926\" id=\"mega-menu-item-2926\"><a class=\"mega-menu-link\" href=\"#\" aria-expanded=\"false\" aria-controls=\"mega-sub-menu-2926\">PELAWAT<span class=\"mega-indicator\" aria-hidden=\"true\"><\/span><\/a>\n<ul class=\"mega-sub-menu\" id='mega-sub-menu-2926'>\n<li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2927\" id=\"mega-menu-item-2927\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/info-sik-mds\/\">Info Sik<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2928\" id=\"mega-menu-item-2928\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/pengangkutan-mds\/\">Pengangkutan<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-has-children mega-menu-item-2929\" id=\"mega-menu-item-2929\"><a class=\"mega-menu-link\" href=\"#\" aria-expanded=\"false\" aria-controls=\"mega-sub-menu-2929\">Destinasi Menarik<span class=\"mega-indicator\" aria-hidden=\"true\"><\/span><\/a>\n\t<ul class=\"mega-sub-menu\" id='mega-sub-menu-2929'>\n<li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2930\" id=\"mega-menu-item-2930\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/peta-destinasi-menarik-4\/\">Peta Destinasi Menarik<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-has-children mega-menu-item-2931\" id=\"mega-menu-item-2931\"><a class=\"mega-menu-link\" href=\"#\" aria-expanded=\"false\" aria-controls=\"mega-sub-menu-2931\">Penginapan<span class=\"mega-indicator\" aria-hidden=\"true\"><\/span><\/a>\n\t\t<ul class=\"mega-sub-menu\" id='mega-sub-menu-2931'>\n<li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-12387\" id=\"mega-menu-item-12387\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/sik-inn-mds\/\">Sik Inn<\/a><\/li>\t\t<\/ul>\n<\/li>\t<\/ul>\n<\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2932\" id=\"mega-menu-item-2932\"><a class=\"mega-menu-link\" href=\"#\">Kaji Selidik Kepuasan Pelanggan<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2933\" id=\"mega-menu-item-2933\"><a class=\"mega-menu-link\" href=\"#\">Beli-belah<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2934\" id=\"mega-menu-item-2934\"><a class=\"mega-menu-link\" href=\"#\">Rekreasi<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-has-children mega-menu-item-2935\" id=\"mega-menu-item-2935\"><a class=\"mega-menu-link\" href=\"#\" aria-expanded=\"false\" aria-controls=\"mega-sub-menu-2935\">Tempat Ibadat<span class=\"mega-indicator\" aria-hidden=\"true\"><\/span><\/a>\n\t<ul class=\"mega-sub-menu\" id='mega-sub-menu-2935'>\n<li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2936\" id=\"mega-menu-item-2936\"><a class=\"mega-menu-link\" href=\"#\">Masjid<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2937\" id=\"mega-menu-item-2937\"><a class=\"mega-menu-link\" href=\"#\">Tokong<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2938\" id=\"mega-menu-item-2938\"><a class=\"mega-menu-link\" href=\"#\">Kuil<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2939\" id=\"mega-menu-item-2939\"><a class=\"mega-menu-link\" href=\"#\">Gereja<\/a><\/li>\t<\/ul>\n<\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-has-children mega-menu-item-2940\" id=\"mega-menu-item-2940\"><a class=\"mega-menu-link\" href=\"#\" aria-expanded=\"false\" aria-controls=\"mega-sub-menu-2940\">Pendidikan<span class=\"mega-indicator\" aria-hidden=\"true\"><\/span><\/a>\n\t<ul class=\"mega-sub-menu\" id='mega-sub-menu-2940'>\n<li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2941\" id=\"mega-menu-item-2941\"><a class=\"mega-menu-link\" href=\"#\">Institusi Pengajian Tinggi<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2942\" id=\"mega-menu-item-2942\"><a class=\"mega-menu-link\" href=\"#\">Pusat Kemahiran<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2943\" id=\"mega-menu-item-2943\"><a class=\"mega-menu-link\" href=\"#\">Sekolah<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2944\" id=\"mega-menu-item-2944\"><a class=\"mega-menu-link\" href=\"#\">Taska<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2945\" id=\"mega-menu-item-2945\"><a class=\"mega-menu-link\" href=\"#\">Tabika<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2946\" id=\"mega-menu-item-2946\"><a class=\"mega-menu-link\" href=\"#\">Perpustakaan<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2947\" id=\"mega-menu-item-2947\"><a class=\"mega-menu-link\" href=\"#\">Pejabat Pelajaran Daerah<\/a><\/li>\t<\/ul>\n<\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-has-children mega-menu-item-2948\" id=\"mega-menu-item-2948\"><a class=\"mega-menu-link\" href=\"#\" aria-expanded=\"false\" aria-controls=\"mega-sub-menu-2948\">MEDIA@PBT<span class=\"mega-indicator\" aria-hidden=\"true\"><\/span><\/a>\n\t<ul class=\"mega-sub-menu\" id='mega-sub-menu-2948'>\n<li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2949\" id=\"mega-menu-item-2949\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/pengumuman-mds\/\">Pengumuman<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2950\" id=\"mega-menu-item-2950\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/arkib-pengumuman-mds\/\">Arkib Pengumuman<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-2951\" id=\"mega-menu-item-2951\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/berita-mds\/\">Berita<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-12351\" id=\"mega-menu-item-12351\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/arkib-berita-mds\/\">Arkib Berita<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-has-children mega-menu-item-2952\" id=\"mega-menu-item-2952\"><a class=\"mega-menu-link\" href=\"#\" aria-expanded=\"false\" aria-controls=\"mega-sub-menu-2952\">Galeri<span class=\"mega-indicator\" aria-hidden=\"true\"><\/span><\/a>\n\t\t<ul class=\"mega-sub-menu\" id='mega-sub-menu-2952'>\n<li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-12357\" id=\"mega-menu-item-12357\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/empangan-gubir-mds\/\">Empangan Gubir<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-12359\" id=\"mega-menu-item-12359\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/empangan-muda-mds\/\">Empangan Muda<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-12366\" id=\"mega-menu-item-12366\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/hutan-simpan-ulu-muda-mds\/\">Hutan Simpan Ulu Muda<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-12374\" id=\"mega-menu-item-12374\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/lata-embun-mds\/\">Lata Embun<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-12376\" id=\"mega-menu-item-12376\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/lata-lembu-emas-mds\/\">Lata Lembu Emas<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-12392\" id=\"mega-menu-item-12392\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/tasik-beris-mds\/\">Tasik Beris<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-12397\" id=\"mega-menu-item-12397\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/lata-mengkuang-mds\/\">Lata Mengkuang<\/a><\/li>\t\t<\/ul>\n<\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-12344\" id=\"mega-menu-item-12344\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/arkib-galeri-mds\/\">Arkib Galeri<\/a><\/li>\t<\/ul>\n<\/li><\/ul>\n<\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-align-bottom-left mega-menu-flyout mega-menu-item-2953\" id=\"mega-menu-item-2953\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/soalan-lazim-mds\/\">SOALAN LAZIM<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-align-bottom-left mega-menu-flyout mega-menu-item-2954\" id=\"mega-menu-item-2954\"><a class=\"mega-menu-link\" href=\"https:\/\/pbt.kedah.gov.my\/index.php\/hubungi-kami-mds\/\">HUBUNGI KAMI<\/a><\/li><\/ul><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7fdb4e5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7fdb4e5\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9fff330\" data-id=\"9fff330\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d1eebd elementor-widget elementor-widget-text-editor\" data-id=\"0d1eebd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>Piagam Pelanggan Majlis Daerah Sik<\/h4><ol><li>Memastikan semua aduan awam yang diterima akan diurus dalam tempoh masa 1-3 hari bekerja.<\/li><li>Semua aduan am kesihatan dalam bidang kuasa Majlis akan disiasat serta diambil tindakan dalam tempoh masa 7 hari bekerja.<\/li><li>Memproses dan meluluskan permohonan permit \/ lesen perniagaan:<table><tbody><tr><td width=\"43\"><p>BIL.<\/p><\/td><td width=\"328\"><p>JENIS PERMOHONAN<\/p><\/td><td width=\"183\"><p>TEMPOH KELULUSAN<\/p><\/td><\/tr><tr><td width=\"43\"><p>1.<\/p><\/td><td width=\"328\"><p>Lesen Tidak Berisiko<\/p><\/td><td width=\"183\"><p>Serta-merta<\/p><\/td><\/tr><tr><td width=\"43\"><p>2.<\/p><\/td><td width=\"328\"><p>Lesen Berisiko Tinggi<\/p><\/td><td width=\"183\"><p>14 Hari Bekerja<\/p><\/td><\/tr><tr><td width=\"43\"><p>3.<\/p><\/td><td width=\"328\"><p>Permit Kaki Lima \/ Kerusi Meja<\/p><\/td><td width=\"183\"><p>1-3 Hari Bekerja<\/p><\/td><\/tr><tr><td width=\"43\"><p>4.<\/p><\/td><td width=\"328\"><p>Permit \/ Lesen Pasar Malam<\/p><\/td><td width=\"183\"><p>Serta-merta<\/p><\/td><\/tr><tr><td width=\"43\"><p>5.<\/p><\/td><td width=\"328\"><p>Permit Penganjuran Sementara<\/p><\/td><td width=\"183\"><p>7-14 Hari Bekerja<\/p><\/td><\/tr><\/tbody><\/table><\/li><li>Memproses permohonan Pindah Milik Pegangan dalam tempoh 1 hari.<\/li><li>Kelulusan Kebenaran Merancang \/ Kelulusan Pelan Bangunan \/ Kelulusan Pelan Jalan Dan Perparitan \/ Kelulusan Pelan Kerja Tanah seperti berikut:<table width=\"556\"><tbody><tr><td width=\"46\"><p>BIL.<\/p><\/td><td width=\"302\"><p>KATEGORI<\/p><\/td><td width=\"104\"><p>TEMPOH \/ MINIMA<\/p><\/td><td width=\"104\"><p>TEMPOH MAKSIMA<\/p><\/td><\/tr><tr><td width=\"46\"><p>1.<\/p><\/td><td width=\"302\"><p>Kelulusan Kebenaran Merancang (Kecil)<\/p><\/td><td width=\"104\"><p>44 hari<\/p><\/td><td width=\"104\"><p>86 HAri<\/p><\/td><\/tr><tr><td width=\"46\"><p>2.<\/p><\/td><td width=\"302\"><p>Kelulusan Kebenaran Merancang (Sederhana)<\/p><\/td><td width=\"104\"><p>57 Hari<\/p><\/td><td width=\"104\"><p>99 Hari<\/p><\/td><\/tr><tr><td width=\"46\"><p>3.<\/p><\/td><td width=\"302\"><p>Kelulusan Kebenaran Merancang (Besar A)<\/p><\/td><td width=\"104\"><p>&#8211;<\/p><\/td><td width=\"104\"><p>300 Hari<\/p><\/td><\/tr><tr><td width=\"46\"><p>4.<\/p><\/td><td width=\"302\"><p>Kelulusan Kebenaran Merancang (Besar B)<\/p><\/td><td width=\"104\"><p>73 Hari<\/p><\/td><td width=\"104\"><p>115 Hari<\/p><\/td><\/tr><tr><td width=\"46\"><p>5.<\/p><\/td><td width=\"302\"><p>Kelulusan Pelan Bangunan<\/p><\/td><td width=\"104\"><p>50 Hari<\/p><\/td><td width=\"104\"><p>92 Hari<\/p><\/td><\/tr><tr><td width=\"46\"><p>6.<\/p><\/td><td width=\"302\"><p>Kelulusan Pelan Jalan dan Perparitan<\/p><\/td><td width=\"104\"><p>50 Hari<\/p><\/td><td width=\"104\"><p>92 Hari<\/p><\/td><\/tr><tr><td width=\"46\"><p>7.<\/p><\/td><td width=\"302\"><p>Kelulusan Pelan Kerja Tanah<\/p><\/td><td width=\"104\"><p>50 Hari<\/p><\/td><td width=\"104\"><p>92 Hari<\/p><\/td><\/tr><\/tbody><\/table><br \/><br \/><\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Piagam Pelanggan Majlis Daerah Sik Memastikan semua aduan awam yang diterima akan diurus dalam tempoh masa 1-3 hari bekerja. Semua&#8230;<\/p>\n","protected":false},"author":7,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-10118","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/pbt.kedah.gov.my\/index.php\/wp-json\/wp\/v2\/pages\/10118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pbt.kedah.gov.my\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/pbt.kedah.gov.my\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/pbt.kedah.gov.my\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/pbt.kedah.gov.my\/index.php\/wp-json\/wp\/v2\/comments?post=10118"}],"version-history":[{"count":30,"href":"https:\/\/pbt.kedah.gov.my\/index.php\/wp-json\/wp\/v2\/pages\/10118\/revisions"}],"predecessor-version":[{"id":89676,"href":"https:\/\/pbt.kedah.gov.my\/index.php\/wp-json\/wp\/v2\/pages\/10118\/revisions\/89676"}],"wp:attachment":[{"href":"https:\/\/pbt.kedah.gov.my\/index.php\/wp-json\/wp\/v2\/media?parent=10118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}